{"id":8281,"date":"2025-05-07T15:21:28","date_gmt":"2025-05-07T22:21:28","guid":{"rendered":"https:\/\/conslosangeles.esteri.it\/?page_id=8281"},"modified":"2026-06-29T11:31:24","modified_gmt":"2026-06-29T18:31:24","slug":"consula-register-citizenship-department","status":"publish","type":"page","link":"https:\/\/conslosangeles.esteri.it\/en\/servizi-consolari-e-visti\/servizi-per-il-cittadino-italiano\/altri-servizi\/albo-consolare\/consula-register-citizenship-department\/","title":{"rendered":"Consular register Citizenship Department"},"content":{"rendered":"<p><strong>AVVISI DI GIACENZA DOCUMENTI<\/strong><\/p>\n<p>Avviso di giacenza documenti: ZITO Michael Francis (pubblicato il 29\/06\/2026 &#8211;\u00a0 ritiro entro il 20\/07\/2026)<\/p>\n<p>_______________________________________________________________________________<\/p>\n<p>Avviso di giacenza documenti: COWELL Jason Frank (pubblicato il 09\/06\/2026 &#8211;\u00a0 ritiro entro il 29\/06\/2026)<\/p>\n<p>Avviso di giacenza documenti: CHIAPPINELLI Denise Louise (pubblicato il 09\/06\/2026 &#8211;\u00a0 ritiro entro il 29\/06\/2026)<\/p>\n<p>Avviso di giacenza documenti: MINTER Casey Paoli (pubblicato il 09\/06\/2026 &#8211;\u00a0 ritiro entro il 29\/06\/2026)<\/p>\n<p>Avviso di giacenza documenti: ARECCO Daniel (pubblicato il 09\/06\/2026 &#8211;\u00a0 ritiro entro il 29\/06\/2026)<\/p>\n<p>Avviso di giacenza documenti: RANSDELL John Presley (pubblicato il 09\/06\/2026 &#8211;\u00a0 ritiro entro il 29\/06\/2026)<\/p>\n<p>_______________________________________________________________________________<\/p>\n<p>Avviso di giacenza documenti: MASTRO Charles (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: GOLGART Rylie Alecia (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: SCANGARELLO Richard Rosario (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: SOMERS Violet Grace (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: GRISPINO Cynthia Marie (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: CROSTA David Michael (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: SCOTT Anthony Michael (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: CAMORIANO John Kelly (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: ODOM Beau Andrew (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: YUHAS John Vernon (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: LOGAN Shelley Laura (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: SCANGARELLO Richard Rosario (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: LIUZZI Michael David (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: SILVESTRO John Thomas (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: VEGES Sheri Lee (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: REHFELD James Laurence (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: PECANO Melissa Ann (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: DI MARIA Renee Josephine (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: FERRACO Adam James (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: DALLAFIOR Rhiannon Joy (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: MARTINEZ Andrew Paul (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: BERMAN Domenica Burgeno (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: CRAIG Christian Joseph (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: THOMAS Monique Josephine (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: GALLATI Timothy Lynch (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: FASSI Lauren Ann (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: MELBY Michael James (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: ROSENTHAL Amanda Hope (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: OLSON Whitney Matija (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: TENNANT SCULL Anna Theresa (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: GANNET Gabriella Lattanzi (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: NASCA Jessica Rose (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: FERULLO Gianni (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: ROMEO Madison Elizabeth (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>Avviso di giacenza documenti: CAMPAGNA Cristina Jean (pubblicato il 04\/05\/2026 &#8211;\u00a0 ritiro entro il 25\/05\/2026)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"AVVISI DI GIACENZA DOCUMENTI Avviso di giacenza documenti: ZITO Michael Francis (pubblicato il 29\/06\/2026 &#8211;\u00a0 ritiro entro il 20\/07\/2026) _______________________________________________________________________________ Avviso di giacenza documenti: COWELL Jason Frank (pubblicato il 09\/06\/2026 &#8211;\u00a0 ritiro entro il 29\/06\/2026) Avviso di giacenza documenti: CHIAPPINELLI Denise Louise (pubblicato il 09\/06\/2026 &#8211;\u00a0 ritiro entro il 29\/06\/2026) Avviso di giacenza documenti: MINTER [&hellip;]","protected":false},"author":3,"featured_media":0,"parent":232,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8281","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/conslosangeles.esteri.it\/en\/wp-json\/wp\/v2\/pages\/8281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conslosangeles.esteri.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/conslosangeles.esteri.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/conslosangeles.esteri.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conslosangeles.esteri.it\/en\/wp-json\/wp\/v2\/comments?post=8281"}],"version-history":[{"count":6,"href":"https:\/\/conslosangeles.esteri.it\/en\/wp-json\/wp\/v2\/pages\/8281\/revisions"}],"predecessor-version":[{"id":10068,"href":"https:\/\/conslosangeles.esteri.it\/en\/wp-json\/wp\/v2\/pages\/8281\/revisions\/10068"}],"up":[{"embeddable":true,"href":"https:\/\/conslosangeles.esteri.it\/en\/wp-json\/wp\/v2\/pages\/232"}],"wp:attachment":[{"href":"https:\/\/conslosangeles.esteri.it\/en\/wp-json\/wp\/v2\/media?parent=8281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}